{"id":1496,"count":1,"description":"","link":"https:\/\/places-ua.com\/kyiv\/vyshneve\/magazyn-zdorovoyi-yizhi-vyshneve\/","name":"\u041c\u0430\u0433\u0430\u0437\u0438\u043d \u0437\u0434\u043e\u0440\u043e\u0432\u043e\u0457 \u0457\u0436\u0456 \u0412\u0438\u0448\u043d\u0435\u0432\u0435","slug":"magazyn-zdorovoyi-yizhi-vyshneve","taxonomy":"category","parent":46,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/places-ua.com\/kyiv\/wp-json\/wp\/v2\/categories\/1496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/places-ua.com\/kyiv\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/places-ua.com\/kyiv\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/places-ua.com\/kyiv\/wp-json\/wp\/v2\/categories\/46"}],"wp:post_type":[{"href":"https:\/\/places-ua.com\/kyiv\/wp-json\/wp\/v2\/posts?categories=1496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}