{"id":2227,"count":17,"description":"","link":"https:\/\/places-ua.com\/kyiv\/city\/pab-kyyiv\/","name":"\u041f\u0430\u0431 \u041a\u0438\u0457\u0432","slug":"pab-kyyiv","taxonomy":"category","parent":27,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/places-ua.com\/kyiv\/wp-json\/wp\/v2\/categories\/2227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/places-ua.com\/kyiv\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/places-ua.com\/kyiv\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/places-ua.com\/kyiv\/wp-json\/wp\/v2\/categories\/27"}],"wp:post_type":[{"href":"https:\/\/places-ua.com\/kyiv\/wp-json\/wp\/v2\/posts?categories=2227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}